{"id":38011,"date":"2017-10-30T15:29:34","date_gmt":"2017-10-30T14:29:34","guid":{"rendered":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/Manual-BNC012.pdf"},"modified":"2017-10-30T15:29:34","modified_gmt":"2017-10-30T14:29:34","slug":"manual-bnc012","status":"inherit","type":"attachment","link":"https:\/\/watch4time.eu\/sv\/?attachment_id=38011","title":{"rendered":"Manual BNC012"},"author":3,"comment_status":"open","ping_status":"closed","template":"","meta":{"_mi_skip_tracking":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.5.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Manual BNC012 - Watch4Time<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/Manual-BNC012.pdf\" \/>\n<meta property=\"og:locale\" content=\"sv_SE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manual BNC012 - Watch4Time\" \/>\n<meta property=\"og:url\" content=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/Manual-BNC012.pdf\" \/>\n<meta property=\"og:site_name\" content=\"Watch4Time\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/watch4time.eu\/#website\",\"url\":\"https:\/\/watch4time.eu\/\",\"name\":\"Watch4Time\",\"description\":\"Exquisite watches for you\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/watch4time.eu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"sv-SE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/Manual-BNC012.pdf#webpage\",\"url\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/Manual-BNC012.pdf\",\"name\":\"Manual BNC012 - Watch4Time\",\"isPartOf\":{\"@id\":\"https:\/\/watch4time.eu\/#website\"},\"datePublished\":\"2017-10-30T14:29:34+00:00\",\"dateModified\":\"2017-10-30T14:29:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/Manual-BNC012.pdf#breadcrumb\"},\"inLanguage\":\"sv-SE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/Manual-BNC012.pdf\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/Manual-BNC012.pdf#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\/\/watch4time.eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Braun Classic BNC012WHWH\",\"item\":\"https:\/\/watch4time.eu\/sv\/shop\/braun-38\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Manual BNC012\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Manual BNC012 - Watch4Time","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/Manual-BNC012.pdf","og_locale":"sv_SE","og_type":"article","og_title":"Manual BNC012 - Watch4Time","og_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/Manual-BNC012.pdf","og_site_name":"Watch4Time","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/watch4time.eu\/#website","url":"https:\/\/watch4time.eu\/","name":"Watch4Time","description":"Exquisite watches for you","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/watch4time.eu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"sv-SE"},{"@type":"WebPage","@id":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/Manual-BNC012.pdf#webpage","url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/Manual-BNC012.pdf","name":"Manual BNC012 - Watch4Time","isPartOf":{"@id":"https:\/\/watch4time.eu\/#website"},"datePublished":"2017-10-30T14:29:34+00:00","dateModified":"2017-10-30T14:29:34+00:00","breadcrumb":{"@id":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/Manual-BNC012.pdf#breadcrumb"},"inLanguage":"sv-SE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/Manual-BNC012.pdf"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/Manual-BNC012.pdf#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/watch4time.eu\/"},{"@type":"ListItem","position":2,"name":"Braun Classic BNC012WHWH","item":"https:\/\/watch4time.eu\/sv\/shop\/braun-38\/"},{"@type":"ListItem","position":3,"name":"Manual BNC012"}]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/Manual-BNC012.pdf'><img width=\"722\" height=\"400\" src=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/Manual-BNC012-pdf-722x400.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"file","mime_type":"application\/pdf","media_details":{"sizes":{"thumbnail":{"file":"Manual-BNC012-pdf-280x155.jpg","width":280,"height":155,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/Manual-BNC012-pdf-280x155.jpg"},"medium":{"file":"Manual-BNC012-pdf-722x400.jpg","width":722,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/Manual-BNC012-pdf-722x400.jpg"},"large":{"file":"Manual-BNC012-pdf-1400x775.jpg","width":1400,"height":775,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/Manual-BNC012-pdf-1400x775.jpg"},"full":{"file":"Manual-BNC012-pdf.jpg","width":1638,"height":907,"mime_type":"application\/pdf","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/Manual-BNC012-pdf.jpg"}}},"post":38003,"source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/Manual-BNC012.pdf","_links":{"self":[{"href":"https:\/\/watch4time.eu\/sv\/wp-json\/wp\/v2\/media\/38011"}],"collection":[{"href":"https:\/\/watch4time.eu\/sv\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/watch4time.eu\/sv\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/watch4time.eu\/sv\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/watch4time.eu\/sv\/wp-json\/wp\/v2\/comments?post=38011"}]}}