{"id":26892,"date":"2017-12-04T11:49:47","date_gmt":"2017-12-04T10:49:47","guid":{"rendered":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT.jpg"},"modified":"2017-12-04T11:49:47","modified_gmt":"2017-12-04T10:49:47","slug":"bn0111whpkl-1_front","status":"inherit","type":"attachment","link":"https:\/\/watch4time.eu\/sv\/?attachment_id=26892#main","title":{"rendered":"BN0111WHPKL (1)_FRONT"},"author":3,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_mi_skip_tracking":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.5.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>BN0111WHPKL (1)_FRONT - Watch4Time<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT.jpg\" \/>\n<meta property=\"og:locale\" content=\"sv_SE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BN0111WHPKL (1)_FRONT - Watch4Time\" \/>\n<meta property=\"og:url\" content=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Watch4Time\" \/>\n<meta property=\"og:image\" content=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/watch4time.eu\/#website\",\"url\":\"https:\/\/watch4time.eu\/\",\"name\":\"Watch4Time\",\"description\":\"Exquisite watches for you\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/watch4time.eu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"sv-SE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT.jpg#webpage\",\"url\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT.jpg\",\"name\":\"BN0111WHPKL (1)_FRONT - Watch4Time\",\"isPartOf\":{\"@id\":\"https:\/\/watch4time.eu\/#website\"},\"datePublished\":\"2017-12-04T10:49:47+00:00\",\"dateModified\":\"2017-12-04T10:49:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT.jpg#breadcrumb\"},\"inLanguage\":\"sv-SE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\/\/watch4time.eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Braun Classic Slim BN0211BKMHL\",\"item\":\"https:\/\/watch4time.eu\/sv\/shop\/braun-classic-slim-2\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BN0111WHPKL (1)_FRONT\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BN0111WHPKL (1)_FRONT - Watch4Time","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT.jpg","og_locale":"sv_SE","og_type":"article","og_title":"BN0111WHPKL (1)_FRONT - Watch4Time","og_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT.jpg","og_site_name":"Watch4Time","og_image":[{"width":1000,"height":1000,"url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/watch4time.eu\/#website","url":"https:\/\/watch4time.eu\/","name":"Watch4Time","description":"Exquisite watches for you","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/watch4time.eu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"sv-SE"},{"@type":"WebPage","@id":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT.jpg#webpage","url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT.jpg","name":"BN0111WHPKL (1)_FRONT - Watch4Time","isPartOf":{"@id":"https:\/\/watch4time.eu\/#website"},"datePublished":"2017-12-04T10:49:47+00:00","dateModified":"2017-12-04T10:49:47+00:00","breadcrumb":{"@id":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT.jpg#breadcrumb"},"inLanguage":"sv-SE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/watch4time.eu\/"},{"@type":"ListItem","position":2,"name":"Braun Classic Slim BN0211BKMHL","item":"https:\/\/watch4time.eu\/sv\/shop\/braun-classic-slim-2\/"},{"@type":"ListItem","position":3,"name":"BN0111WHPKL (1)_FRONT"}]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT.jpg'><img width=\"400\" height=\"400\" src=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT-400x400.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT-400x400.jpg 400w, https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT-280x280.jpg 280w, https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT-768x768.jpg 768w, https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT-800x800.jpg 800w, https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT-100x100.jpg 100w, https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT.jpg 1000w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1000,"height":1000,"file":"2017\/09\/BN0111WHPKL-1_FRONT.jpg","sizes":{"thumbnail":{"file":"BN0111WHPKL-1_FRONT-280x280.jpg","width":280,"height":280,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT-280x280.jpg"},"medium":{"file":"BN0111WHPKL-1_FRONT-400x400.jpg","width":400,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT-400x400.jpg"},"medium_large":{"file":"BN0111WHPKL-1_FRONT-768x768.jpg","width":768,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT-768x768.jpg"},"large":{"file":"BN0111WHPKL-1_FRONT-800x800.jpg","width":800,"height":800,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT-800x800.jpg"},"shop_thumbnail":{"file":"BN0111WHPKL-1_FRONT-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT-100x100.jpg"},"shop_catalog":{"file":"BN0111WHPKL-1_FRONT-247x300.jpg","width":247,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT-247x300.jpg"},"shop_single":{"file":"BN0111WHPKL-1_FRONT-510x600.jpg","width":510,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT-768x768.jpg"},"full":{"file":"BN0111WHPKL-1_FRONT.jpg","width":1000,"height":1000,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":26883,"source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0111WHPKL-1_FRONT.jpg","_links":{"self":[{"href":"https:\/\/watch4time.eu\/sv\/wp-json\/wp\/v2\/media\/26892"}],"collection":[{"href":"https:\/\/watch4time.eu\/sv\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/watch4time.eu\/sv\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/watch4time.eu\/sv\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/watch4time.eu\/sv\/wp-json\/wp\/v2\/comments?post=26892"}]}}