{"id":26813,"date":"2017-09-04T14:14:19","date_gmt":"2017-09-04T12:14:19","guid":{"rendered":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK.jpg"},"modified":"2017-09-04T14:14:19","modified_gmt":"2017-09-04T12:14:19","slug":"bn0211bkmhg-6-case-back","status":"inherit","type":"attachment","link":"https:\/\/watch4time.eu\/sv\/?attachment_id=26813#main","title":{"rendered":"BN0211BKMHG (6) CASE BACK"},"author":3,"comment_status":"open","ping_status":"closed","template":"","meta":{"_mi_skip_tracking":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.5.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>BN0211BKMHG (6) CASE BACK - Watch4Time<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK.jpg\" \/>\n<meta property=\"og:locale\" content=\"sv_SE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BN0211BKMHG (6) CASE BACK - Watch4Time\" \/>\n<meta property=\"og:url\" content=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Watch4Time\" \/>\n<meta property=\"og:image\" content=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/watch4time.eu\/#website\",\"url\":\"https:\/\/watch4time.eu\/\",\"name\":\"Watch4Time\",\"description\":\"Exquisite watches for you\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/watch4time.eu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"sv-SE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK.jpg#webpage\",\"url\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK.jpg\",\"name\":\"BN0211BKMHG (6) CASE BACK - Watch4Time\",\"isPartOf\":{\"@id\":\"https:\/\/watch4time.eu\/#website\"},\"datePublished\":\"2017-09-04T12:14:19+00:00\",\"dateModified\":\"2017-09-04T12:14:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK.jpg#breadcrumb\"},\"inLanguage\":\"sv-SE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\/\/watch4time.eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Braun Classic Slim BN0211BKMHG\",\"item\":\"https:\/\/watch4time.eu\/sv\/shop\/braun-60\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BN0211BKMHG (6) CASE BACK\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BN0211BKMHG (6) CASE BACK - Watch4Time","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK.jpg","og_locale":"sv_SE","og_type":"article","og_title":"BN0211BKMHG (6) CASE BACK - Watch4Time","og_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK.jpg","og_site_name":"Watch4Time","og_image":[{"width":1024,"height":1024,"url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/watch4time.eu\/#website","url":"https:\/\/watch4time.eu\/","name":"Watch4Time","description":"Exquisite watches for you","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/watch4time.eu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"sv-SE"},{"@type":"WebPage","@id":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK.jpg#webpage","url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK.jpg","name":"BN0211BKMHG (6) CASE BACK - Watch4Time","isPartOf":{"@id":"https:\/\/watch4time.eu\/#website"},"datePublished":"2017-09-04T12:14:19+00:00","dateModified":"2017-09-04T12:14:19+00:00","breadcrumb":{"@id":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK.jpg#breadcrumb"},"inLanguage":"sv-SE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/watch4time.eu\/"},{"@type":"ListItem","position":2,"name":"Braun Classic Slim BN0211BKMHG","item":"https:\/\/watch4time.eu\/sv\/shop\/braun-60\/"},{"@type":"ListItem","position":3,"name":"BN0211BKMHG (6) CASE BACK"}]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK.jpg'><img width=\"400\" height=\"400\" src=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK-400x400.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK-400x400.jpg 400w, https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK-280x280.jpg 280w, https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK-768x768.jpg 768w, https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK-800x800.jpg 800w, https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK-130x130.jpg 130w, https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK-600x600.jpg 600w, https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK.jpg 1024w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1024,"height":1024,"file":"2017\/09\/BN0211BKMHG-6-CASE-BACK.jpg","sizes":{"thumbnail":{"file":"BN0211BKMHG-6-CASE-BACK-280x280.jpg","width":280,"height":280,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK-280x280.jpg"},"medium":{"file":"BN0211BKMHG-6-CASE-BACK-400x400.jpg","width":400,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK-400x400.jpg"},"medium_large":{"file":"BN0211BKMHG-6-CASE-BACK-768x768.jpg","width":768,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK-768x768.jpg"},"large":{"file":"BN0211BKMHG-6-CASE-BACK-800x800.jpg","width":800,"height":800,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK-800x800.jpg"},"shop_thumbnail":{"file":"BN0211BKMHG-6-CASE-BACK-130x130.jpg","width":130,"height":130,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK-130x130.jpg"},"shop_catalog":{"file":"BN0211BKMHG-6-CASE-BACK-247x300.jpg","width":247,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK-247x300.jpg"},"shop_single":{"file":"BN0211BKMHG-6-CASE-BACK-600x600.jpg","width":600,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK-600x600.jpg"},"woocommerce_thumbnail":{"file":"BN0211BKMHG-6-CASE-BACK-247x300.jpg","width":247,"height":300,"uncropped":true,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK-247x300.jpg"},"full":{"file":"BN0211BKMHG-6-CASE-BACK.jpg","width":1024,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":26807,"source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/BN0211BKMHG-6-CASE-BACK.jpg","_links":{"self":[{"href":"https:\/\/watch4time.eu\/sv\/wp-json\/wp\/v2\/media\/26813"}],"collection":[{"href":"https:\/\/watch4time.eu\/sv\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/watch4time.eu\/sv\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/watch4time.eu\/sv\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/watch4time.eu\/sv\/wp-json\/wp\/v2\/comments?post=26813"}]}}