{"id":40625,"date":"2019-06-27T15:50:10","date_gmt":"2019-06-27T13:50:10","guid":{"rendered":"https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002.jpg"},"modified":"2019-06-27T15:56:38","modified_gmt":"2019-06-27T13:56:38","slug":"4-sector-ex-42-watch-r3251527002-2","status":"inherit","type":"attachment","link":"https:\/\/watch4time.eu\/no\/?attachment_id=40625#main","title":{"rendered":"4-sector-ex-42-watch-r3251527002"},"author":3,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_mi_skip_tracking":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.5.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>4-sector-ex-42-watch-r3251527002 - Watch4Time<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002.jpg\" \/>\n<meta property=\"og:locale\" content=\"nb_NO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4-sector-ex-42-watch-r3251527002 - Watch4Time\" \/>\n<meta property=\"og:url\" content=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Watch4Time\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-27T13:56:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/watch4time.eu\/#website\",\"url\":\"https:\/\/watch4time.eu\/\",\"name\":\"Watch4Time\",\"description\":\"Exquisite watches for you\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/watch4time.eu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nb-NO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002.jpg#webpage\",\"url\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002.jpg\",\"name\":\"4-sector-ex-42-watch-r3251527002 - Watch4Time\",\"isPartOf\":{\"@id\":\"https:\/\/watch4time.eu\/#website\"},\"datePublished\":\"2019-06-27T13:50:10+00:00\",\"dateModified\":\"2019-06-27T13:56:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002.jpg#breadcrumb\"},\"inLanguage\":\"nb-NO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\/\/watch4time.eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sector Digital EX-42 collection R3251527002\",\"item\":\"https:\/\/watch4time.eu\/no\/shop\/sector-digital-ex-42-collection-r3251527002\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"4-sector-ex-42-watch-r3251527002\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4-sector-ex-42-watch-r3251527002 - Watch4Time","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002.jpg","og_locale":"nb_NO","og_type":"article","og_title":"4-sector-ex-42-watch-r3251527002 - Watch4Time","og_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002.jpg","og_site_name":"Watch4Time","article_modified_time":"2019-06-27T13:56:38+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/watch4time.eu\/#website","url":"https:\/\/watch4time.eu\/","name":"Watch4Time","description":"Exquisite watches for you","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/watch4time.eu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nb-NO"},{"@type":"WebPage","@id":"https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002.jpg#webpage","url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002.jpg","name":"4-sector-ex-42-watch-r3251527002 - Watch4Time","isPartOf":{"@id":"https:\/\/watch4time.eu\/#website"},"datePublished":"2019-06-27T13:50:10+00:00","dateModified":"2019-06-27T13:56:38+00:00","breadcrumb":{"@id":"https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002.jpg#breadcrumb"},"inLanguage":"nb-NO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/watch4time.eu\/"},{"@type":"ListItem","position":2,"name":"Sector Digital EX-42 collection R3251527002","item":"https:\/\/watch4time.eu\/no\/shop\/sector-digital-ex-42-collection-r3251527002\/"},{"@type":"ListItem","position":3,"name":"4-sector-ex-42-watch-r3251527002"}]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002.jpg'><img width=\"400\" height=\"400\" src=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002-400x400.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002-400x400.jpg 400w, https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002-280x280.jpg 280w, https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002-768x768.jpg 768w, https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002-800x800.jpg 800w, https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002-510x510.jpg 510w, https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002-100x100.jpg 100w, https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002.jpg 1500w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1500,"height":1500,"file":"2019\/06\/4-sector-ex-42-watch-r3251527002.jpg","sizes":{"thumbnail":{"file":"4-sector-ex-42-watch-r3251527002-280x280.jpg","width":280,"height":280,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002-280x280.jpg"},"medium":{"file":"4-sector-ex-42-watch-r3251527002-400x400.jpg","width":400,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002-400x400.jpg"},"medium_large":{"file":"4-sector-ex-42-watch-r3251527002-768x768.jpg","width":768,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002-768x768.jpg"},"large":{"file":"4-sector-ex-42-watch-r3251527002-800x800.jpg","width":800,"height":800,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002-800x800.jpg"},"woocommerce_thumbnail":{"file":"4-sector-ex-42-watch-r3251527002-247x300.jpg","width":247,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002-247x300.jpg"},"woocommerce_single":{"file":"4-sector-ex-42-watch-r3251527002-510x510.jpg","width":510,"height":510,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002-510x510.jpg"},"woocommerce_gallery_thumbnail":{"file":"4-sector-ex-42-watch-r3251527002-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002-100x100.jpg"},"shop_catalog":{"file":"4-sector-ex-42-watch-r3251527002-247x300.jpg","width":247,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002-247x300.jpg"},"shop_single":{"file":"4-sector-ex-42-watch-r3251527002-510x510.jpg","width":510,"height":510,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002-510x510.jpg"},"shop_thumbnail":{"file":"4-sector-ex-42-watch-r3251527002-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002-100x100.jpg"},"full":{"file":"4-sector-ex-42-watch-r3251527002.jpg","width":1500,"height":1500,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":40636,"source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2019\/06\/4-sector-ex-42-watch-r3251527002.jpg","_links":{"self":[{"href":"https:\/\/watch4time.eu\/no\/wp-json\/wp\/v2\/media\/40625"}],"collection":[{"href":"https:\/\/watch4time.eu\/no\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/watch4time.eu\/no\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/watch4time.eu\/no\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/watch4time.eu\/no\/wp-json\/wp\/v2\/comments?post=40625"}]}}