{"id":37542,"date":"2017-12-05T15:53:30","date_gmt":"2017-12-05T14:53:30","guid":{"rendered":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC-.jpg"},"modified":"2017-12-05T15:53:30","modified_gmt":"2017-12-05T14:53:30","slug":"bnc008gy-nrc","status":"inherit","type":"attachment","link":"https:\/\/watch4time.eu\/fi\/?attachment_id=37542#main","title":{"rendered":"BNC008GY-NRC"},"author":3,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_mi_skip_tracking":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.5.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>BNC008GY-NRC - Watch4Time<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC-.jpg\" \/>\n<meta property=\"og:locale\" content=\"fi_FI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BNC008GY-NRC - Watch4Time\" \/>\n<meta property=\"og:url\" content=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC-.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Watch4Time\" \/>\n<meta property=\"og:image\" content=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/watch4time.eu\/#website\",\"url\":\"https:\/\/watch4time.eu\/\",\"name\":\"Watch4Time\",\"description\":\"Exquisite watches for you\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/watch4time.eu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fi\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC-.jpg#webpage\",\"url\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC-.jpg\",\"name\":\"BNC008GY-NRC - Watch4Time\",\"isPartOf\":{\"@id\":\"https:\/\/watch4time.eu\/#website\"},\"datePublished\":\"2017-12-05T14:53:30+00:00\",\"dateModified\":\"2017-12-05T14:53:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC-.jpg#breadcrumb\"},\"inLanguage\":\"fi\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC-.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC-.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\/\/watch4time.eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Braun Digital BNC008WHRC\",\"item\":\"https:\/\/watch4time.eu\/fi\/shop\/braun-24\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BNC008GY-NRC\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BNC008GY-NRC - Watch4Time","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC-.jpg","og_locale":"fi_FI","og_type":"article","og_title":"BNC008GY-NRC - Watch4Time","og_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC-.jpg","og_site_name":"Watch4Time","og_image":[{"width":1000,"height":1000,"url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC-.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/watch4time.eu\/#website","url":"https:\/\/watch4time.eu\/","name":"Watch4Time","description":"Exquisite watches for you","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/watch4time.eu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fi"},{"@type":"WebPage","@id":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC-.jpg#webpage","url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC-.jpg","name":"BNC008GY-NRC - Watch4Time","isPartOf":{"@id":"https:\/\/watch4time.eu\/#website"},"datePublished":"2017-12-05T14:53:30+00:00","dateModified":"2017-12-05T14:53:30+00:00","breadcrumb":{"@id":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC-.jpg#breadcrumb"},"inLanguage":"fi","potentialAction":[{"@type":"ReadAction","target":["https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC-.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC-.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/watch4time.eu\/"},{"@type":"ListItem","position":2,"name":"Braun Digital BNC008WHRC","item":"https:\/\/watch4time.eu\/fi\/shop\/braun-24\/"},{"@type":"ListItem","position":3,"name":"BNC008GY-NRC"}]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC-.jpg'><img width=\"400\" height=\"400\" src=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC--400x400.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC--400x400.jpg 400w, https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC--280x280.jpg 280w, https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC--768x768.jpg 768w, https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC--800x800.jpg 800w, https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC--100x100.jpg 100w, https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC-.jpg 1000w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1000,"height":1000,"file":"2017\/08\/BNC008GY-NRC-.jpg","sizes":{"thumbnail":{"file":"BNC008GY-NRC--280x280.jpg","width":280,"height":280,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC--280x280.jpg"},"medium":{"file":"BNC008GY-NRC--400x400.jpg","width":400,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC--400x400.jpg"},"medium_large":{"file":"BNC008GY-NRC--768x768.jpg","width":768,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC--768x768.jpg"},"large":{"file":"BNC008GY-NRC--800x800.jpg","width":800,"height":800,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC--800x800.jpg"},"shop_thumbnail":{"file":"BNC008GY-NRC--100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC--100x100.jpg"},"shop_catalog":{"file":"BNC008GY-NRC--247x300.jpg","width":247,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC--247x300.jpg"},"shop_single":{"file":"BNC008GY-NRC--510x600.jpg","width":510,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC--768x768.jpg"},"woocommerce_thumbnail":{"file":"BNC008GY-NRC--247x300.jpg","width":247,"height":300,"uncropped":true,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC--247x300.jpg"},"full":{"file":"BNC008GY-NRC-.jpg","width":1000,"height":1000,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC-.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":37533,"source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/BNC008GY-NRC-.jpg","_links":{"self":[{"href":"https:\/\/watch4time.eu\/fi\/wp-json\/wp\/v2\/media\/37542"}],"collection":[{"href":"https:\/\/watch4time.eu\/fi\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/watch4time.eu\/fi\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/watch4time.eu\/fi\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/watch4time.eu\/fi\/wp-json\/wp\/v2\/comments?post=37542"}]}}