{"id":11145,"date":"2017-10-30T14:01:31","date_gmt":"2017-10-30T13:01:31","guid":{"rendered":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/Manual-BNC007.pdf"},"modified":"2017-10-30T14:01:31","modified_gmt":"2017-10-30T13:01:31","slug":"manual-bnc007-2","status":"inherit","type":"attachment","link":"https:\/\/watch4time.eu\/en\/?attachment_id=11145","title":{"rendered":"Manual BNC007"},"author":3,"comment_status":"open","ping_status":"closed","template":"","meta":{"_mi_skip_tracking":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.5.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Manual BNC007 - Watch4Time<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/Manual-BNC007.pdf\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manual BNC007 - Watch4Time\" \/>\n<meta property=\"og:url\" content=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/Manual-BNC007.pdf\" \/>\n<meta property=\"og:site_name\" content=\"Watch4Time\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/watch4time.eu\/#website\",\"url\":\"https:\/\/watch4time.eu\/\",\"name\":\"Watch4Time\",\"description\":\"Exquisite watches for you\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/watch4time.eu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/Manual-BNC007.pdf#webpage\",\"url\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/Manual-BNC007.pdf\",\"name\":\"Manual BNC007 - Watch4Time\",\"isPartOf\":{\"@id\":\"https:\/\/watch4time.eu\/#website\"},\"datePublished\":\"2017-10-30T13:01:31+00:00\",\"dateModified\":\"2017-10-30T13:01:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/Manual-BNC007.pdf#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/Manual-BNC007.pdf\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/Manual-BNC007.pdf#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\/\/watch4time.eu\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Braun\",\"item\":\"https:\/\/watch4time.eu\/en\/shop\/braun-68\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Manual BNC007\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Manual BNC007 - Watch4Time","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/Manual-BNC007.pdf","og_locale":"en_US","og_type":"article","og_title":"Manual BNC007 - Watch4Time","og_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/Manual-BNC007.pdf","og_site_name":"Watch4Time","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/watch4time.eu\/#website","url":"https:\/\/watch4time.eu\/","name":"Watch4Time","description":"Exquisite watches for you","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/watch4time.eu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/Manual-BNC007.pdf#webpage","url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/Manual-BNC007.pdf","name":"Manual BNC007 - Watch4Time","isPartOf":{"@id":"https:\/\/watch4time.eu\/#website"},"datePublished":"2017-10-30T13:01:31+00:00","dateModified":"2017-10-30T13:01:31+00:00","breadcrumb":{"@id":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/Manual-BNC007.pdf#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/Manual-BNC007.pdf"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/Manual-BNC007.pdf#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/watch4time.eu\/en\/"},{"@type":"ListItem","position":2,"name":"Braun","item":"https:\/\/watch4time.eu\/en\/shop\/braun-68\/"},{"@type":"ListItem","position":3,"name":"Manual BNC007"}]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/Manual-BNC007.pdf'><img width=\"707\" height=\"400\" src=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/Manual-BNC007-pdf-707x400.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"file","mime_type":"application\/pdf","media_details":{"sizes":{"thumbnail":{"file":"Manual-BNC007-pdf-280x158.jpg","width":280,"height":158,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/Manual-BNC007-pdf-280x158.jpg"},"medium":{"file":"Manual-BNC007-pdf-707x400.jpg","width":707,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/Manual-BNC007-pdf-707x400.jpg"},"large":{"file":"Manual-BNC007-pdf-1400x792.jpg","width":1400,"height":792,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/Manual-BNC007-pdf-1400x792.jpg"},"full":{"file":"Manual-BNC007-pdf.jpg","width":1871,"height":1058,"mime_type":"application\/pdf","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/Manual-BNC007-pdf.jpg"}}},"post":10415,"source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/Manual-BNC007.pdf","_links":{"self":[{"href":"https:\/\/watch4time.eu\/en\/wp-json\/wp\/v2\/media\/11145"}],"collection":[{"href":"https:\/\/watch4time.eu\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/watch4time.eu\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/watch4time.eu\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/watch4time.eu\/en\/wp-json\/wp\/v2\/comments?post=11145"}]}}