{"id":29078,"date":"2018-03-20T13:11:22","date_gmt":"2018-03-20T12:11:22","guid":{"rendered":"https:\/\/watch4time.eu\/shop\/danish-design-406\/"},"modified":"2018-03-20T13:11:22","modified_gmt":"2018-03-20T12:11:22","slug":"danish-design-406","status":"publish","type":"product","link":"https:\/\/watch4time.eu\/de\/shop\/danish-design-406\/","title":{"rendered":"Danish Design London IV12Q1235"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>IV12Q1235<\/p>\n<p>&nbsp;<\/p>\n<p>Diese schlichte und stilvolle Uhr von Danish Design verf\u00fcgt \u00fcber eine Edelstahlbox mit wei\u00dfem Zifferblatt mit silbernen Zeigern und Zeitstempeln, Mineralglas und ein braunes Lederarmband.<\/p>\n","protected":false},"featured_media":19760,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_mi_skip_tracking":false},"product_cat":[644,495,522],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.5.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Danish Design London IV12Q1235 - Watch4Time<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/watch4time.eu\/de\/shop\/danish-design-406\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Danish Design London IV12Q1235 - Watch4Time\" \/>\n<meta property=\"og:description\" content=\"IV12Q1235  &nbsp;  Diese schlichte und stilvolle Uhr von Danish Design verf\u00fcgt \u00fcber eine Edelstahlbox mit wei\u00dfem Zifferblatt mit silbernen Zeigern und Zeitstempeln, Mineralglas und ein braunes Lederarmband.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/watch4time.eu\/de\/shop\/danish-design-406\/\" \/>\n<meta property=\"og:site_name\" content=\"Watch4Time\" \/>\n<meta property=\"og:image\" content=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2018\/03\/IV12Q1235.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/watch4time.eu\/#website\",\"url\":\"https:\/\/watch4time.eu\/\",\"name\":\"Watch4Time\",\"description\":\"Exquisite watches for you\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/watch4time.eu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/watch4time.eu\/de\/shop\/danish-design-406\/#primaryimage\",\"inLanguage\":\"de\",\"url\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2018\/03\/IV12Q1235.jpg\",\"contentUrl\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2018\/03\/IV12Q1235.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/watch4time.eu\/de\/shop\/danish-design-406\/#webpage\",\"url\":\"https:\/\/watch4time.eu\/de\/shop\/danish-design-406\/\",\"name\":\"Danish Design London IV12Q1235 - Watch4Time\",\"isPartOf\":{\"@id\":\"https:\/\/watch4time.eu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/watch4time.eu\/de\/shop\/danish-design-406\/#primaryimage\"},\"datePublished\":\"2018-03-20T12:11:22+00:00\",\"dateModified\":\"2018-03-20T12:11:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/watch4time.eu\/de\/shop\/danish-design-406\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/watch4time.eu\/de\/shop\/danish-design-406\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/watch4time.eu\/de\/shop\/danish-design-406\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\/\/watch4time.eu\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/watch4time.eu\/de\/shop-de\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Danish Design London IV12Q1235\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Danish Design London IV12Q1235 - Watch4Time","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/watch4time.eu\/de\/shop\/danish-design-406\/","og_locale":"de_DE","og_type":"article","og_title":"Danish Design London IV12Q1235 - Watch4Time","og_description":"IV12Q1235  &nbsp;  Diese schlichte und stilvolle Uhr von Danish Design verf\u00fcgt \u00fcber eine Edelstahlbox mit wei\u00dfem Zifferblatt mit silbernen Zeigern und Zeitstempeln, Mineralglas und ein braunes Lederarmband.","og_url":"https:\/\/watch4time.eu\/de\/shop\/danish-design-406\/","og_site_name":"Watch4Time","og_image":[{"width":1000,"height":1000,"url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2018\/03\/IV12Q1235.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/watch4time.eu\/#website","url":"https:\/\/watch4time.eu\/","name":"Watch4Time","description":"Exquisite watches for you","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/watch4time.eu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","@id":"https:\/\/watch4time.eu\/de\/shop\/danish-design-406\/#primaryimage","inLanguage":"de","url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2018\/03\/IV12Q1235.jpg","contentUrl":"https:\/\/watch4time.eu\/wp-content\/uploads\/2018\/03\/IV12Q1235.jpg","width":1000,"height":1000},{"@type":"WebPage","@id":"https:\/\/watch4time.eu\/de\/shop\/danish-design-406\/#webpage","url":"https:\/\/watch4time.eu\/de\/shop\/danish-design-406\/","name":"Danish Design London IV12Q1235 - Watch4Time","isPartOf":{"@id":"https:\/\/watch4time.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/watch4time.eu\/de\/shop\/danish-design-406\/#primaryimage"},"datePublished":"2018-03-20T12:11:22+00:00","dateModified":"2018-03-20T12:11:22+00:00","breadcrumb":{"@id":"https:\/\/watch4time.eu\/de\/shop\/danish-design-406\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/watch4time.eu\/de\/shop\/danish-design-406\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/watch4time.eu\/de\/shop\/danish-design-406\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/watch4time.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/watch4time.eu\/de\/shop-de\/"},{"@type":"ListItem","position":3,"name":"Danish Design London IV12Q1235"}]}]}},"_links":{"self":[{"href":"https:\/\/watch4time.eu\/de\/wp-json\/wp\/v2\/product\/29078"}],"collection":[{"href":"https:\/\/watch4time.eu\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/watch4time.eu\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/watch4time.eu\/de\/wp-json\/wp\/v2\/comments?post=29078"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/watch4time.eu\/de\/wp-json\/wp\/v2\/media\/19760"}],"wp:attachment":[{"href":"https:\/\/watch4time.eu\/de\/wp-json\/wp\/v2\/media?parent=29078"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/watch4time.eu\/de\/wp-json\/wp\/v2\/product_cat?post=29078"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/watch4time.eu\/de\/wp-json\/wp\/v2\/product_tag?post=29078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}