{"id":17658,"date":"2017-09-01T15:33:43","date_gmt":"2017-09-01T13:33:43","guid":{"rendered":"https:\/\/watch4time.eu\/shop\/edox-les-bemonts-40\/"},"modified":"2017-09-01T15:33:43","modified_gmt":"2017-09-01T13:33:43","slug":"edox-les-bemonts-40","status":"publish","type":"product","link":"https:\/\/watch4time.eu\/de\/shop\/edox-les-bemonts-40\/","title":{"rendered":"Edox Les B\u00e9monts"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>85021-37R-BUIR<\/p>\n<p>&nbsp;<\/p>\n<p>Uhr mit Ros\u00e9gold Zuschauer und Zeitmarken auf ein blau w\u00e4hlen mit sichtbar Uhrwerk. Die Uhr hat ein Ros\u00e9gold box aus edelstahl und ein blau Lederarmband mit Alligator-look.<\/p>\n<p>&nbsp;<\/p>\n<p>Wenn Sie dieses Produkt kaufen, erwarten wir eine l\u00e4ngere Lieferzeit.<\/p>\n","protected":false},"featured_media":12484,"comment_status":"open","ping_status":"closed","template":"","meta":{"_mi_skip_tracking":false},"product_cat":[646,548,563,522],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.5.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Edox Les B\u00e9monts - Watch4Time<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/watch4time.eu\/de\/shop\/edox-les-bemonts-40\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Edox Les B\u00e9monts - Watch4Time\" \/>\n<meta property=\"og:description\" content=\"85021-37R-BUIR  &nbsp;  Uhr mit Ros\u00e9gold Zuschauer und Zeitmarken auf ein blau w\u00e4hlen mit sichtbar Uhrwerk. Die Uhr hat ein Ros\u00e9gold box aus edelstahl und ein blau Lederarmband mit Alligator-look.  &nbsp;  Wenn Sie dieses Produkt kaufen, erwarten wir eine l\u00e4ngere Lieferzeit.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/watch4time.eu\/de\/shop\/edox-les-bemonts-40\/\" \/>\n<meta property=\"og:site_name\" content=\"Watch4Time\" \/>\n<meta property=\"og:image\" content=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/85021-37r-buir-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/watch4time.eu\/#website\",\"url\":\"https:\/\/watch4time.eu\/\",\"name\":\"Watch4Time\",\"description\":\"Exquisite watches for you\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/watch4time.eu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/watch4time.eu\/de\/shop\/edox-les-bemonts-40\/#primaryimage\",\"inLanguage\":\"de\",\"url\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/85021-37r-buir-1.jpg\",\"contentUrl\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/85021-37r-buir-1.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/watch4time.eu\/de\/shop\/edox-les-bemonts-40\/#webpage\",\"url\":\"https:\/\/watch4time.eu\/de\/shop\/edox-les-bemonts-40\/\",\"name\":\"Edox Les B\u00e9monts - Watch4Time\",\"isPartOf\":{\"@id\":\"https:\/\/watch4time.eu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/watch4time.eu\/de\/shop\/edox-les-bemonts-40\/#primaryimage\"},\"datePublished\":\"2017-09-01T13:33:43+00:00\",\"dateModified\":\"2017-09-01T13:33:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/watch4time.eu\/de\/shop\/edox-les-bemonts-40\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/watch4time.eu\/de\/shop\/edox-les-bemonts-40\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/watch4time.eu\/de\/shop\/edox-les-bemonts-40\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\/\/watch4time.eu\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/watch4time.eu\/de\/shop-de\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Edox Les B\u00e9monts\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Edox Les B\u00e9monts - Watch4Time","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/watch4time.eu\/de\/shop\/edox-les-bemonts-40\/","og_locale":"de_DE","og_type":"article","og_title":"Edox Les B\u00e9monts - Watch4Time","og_description":"85021-37R-BUIR  &nbsp;  Uhr mit Ros\u00e9gold Zuschauer und Zeitmarken auf ein blau w\u00e4hlen mit sichtbar Uhrwerk. Die Uhr hat ein Ros\u00e9gold box aus edelstahl und ein blau Lederarmband mit Alligator-look.  &nbsp;  Wenn Sie dieses Produkt kaufen, erwarten wir eine l\u00e4ngere Lieferzeit.","og_url":"https:\/\/watch4time.eu\/de\/shop\/edox-les-bemonts-40\/","og_site_name":"Watch4Time","og_image":[{"width":1000,"height":1000,"url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/85021-37r-buir-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/watch4time.eu\/#website","url":"https:\/\/watch4time.eu\/","name":"Watch4Time","description":"Exquisite watches for you","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/watch4time.eu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","@id":"https:\/\/watch4time.eu\/de\/shop\/edox-les-bemonts-40\/#primaryimage","inLanguage":"de","url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/85021-37r-buir-1.jpg","contentUrl":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/09\/85021-37r-buir-1.jpg","width":1000,"height":1000},{"@type":"WebPage","@id":"https:\/\/watch4time.eu\/de\/shop\/edox-les-bemonts-40\/#webpage","url":"https:\/\/watch4time.eu\/de\/shop\/edox-les-bemonts-40\/","name":"Edox Les B\u00e9monts - Watch4Time","isPartOf":{"@id":"https:\/\/watch4time.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/watch4time.eu\/de\/shop\/edox-les-bemonts-40\/#primaryimage"},"datePublished":"2017-09-01T13:33:43+00:00","dateModified":"2017-09-01T13:33:43+00:00","breadcrumb":{"@id":"https:\/\/watch4time.eu\/de\/shop\/edox-les-bemonts-40\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/watch4time.eu\/de\/shop\/edox-les-bemonts-40\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/watch4time.eu\/de\/shop\/edox-les-bemonts-40\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/watch4time.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/watch4time.eu\/de\/shop-de\/"},{"@type":"ListItem","position":3,"name":"Edox Les B\u00e9monts"}]}]}},"_links":{"self":[{"href":"https:\/\/watch4time.eu\/de\/wp-json\/wp\/v2\/product\/17658"}],"collection":[{"href":"https:\/\/watch4time.eu\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/watch4time.eu\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/watch4time.eu\/de\/wp-json\/wp\/v2\/comments?post=17658"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/watch4time.eu\/de\/wp-json\/wp\/v2\/media\/12484"}],"wp:attachment":[{"href":"https:\/\/watch4time.eu\/de\/wp-json\/wp\/v2\/media?parent=17658"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/watch4time.eu\/de\/wp-json\/wp\/v2\/product_cat?post=17658"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/watch4time.eu\/de\/wp-json\/wp\/v2\/product_tag?post=17658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}