{"id":6668,"date":"2017-08-30T10:55:06","date_gmt":"2017-08-30T08:55:06","guid":{"rendered":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120.jpg"},"modified":"2018-01-22T12:01:06","modified_gmt":"2018-01-22T11:01:06","slug":"01-1041-120-2","status":"inherit","type":"attachment","link":"https:\/\/watch4time.eu\/de\/?attachment_id=6668#main","title":{"rendered":"01.1041.120"},"author":3,"comment_status":"open","ping_status":"closed","template":"","meta":{"_mi_skip_tracking":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.5.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>01.1041.120 - Watch4Time<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120.jpg\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"01.1041.120 - Watch4Time\" \/>\n<meta property=\"og:url\" content=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Watch4Time\" \/>\n<meta property=\"article:modified_time\" content=\"2018-01-22T11:01:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/watch4time.eu\/#website\",\"url\":\"https:\/\/watch4time.eu\/\",\"name\":\"Watch4Time\",\"description\":\"Exquisite watches for you\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/watch4time.eu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120.jpg#webpage\",\"url\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120.jpg\",\"name\":\"01.1041.120 - Watch4Time\",\"isPartOf\":{\"@id\":\"https:\/\/watch4time.eu\/#website\"},\"datePublished\":\"2017-08-30T08:55:06+00:00\",\"dateModified\":\"2018-01-22T11:01:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120.jpg#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\/\/watch4time.eu\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wenger Urban Classic\",\"item\":\"https:\/\/watch4time.eu\/de\/shop\/wenger-urban-classic\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"01.1041.120\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"01.1041.120 - Watch4Time","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120.jpg","og_locale":"de_DE","og_type":"article","og_title":"01.1041.120 - Watch4Time","og_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120.jpg","og_site_name":"Watch4Time","article_modified_time":"2018-01-22T11:01:06+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/watch4time.eu\/#website","url":"https:\/\/watch4time.eu\/","name":"Watch4Time","description":"Exquisite watches for you","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/watch4time.eu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120.jpg#webpage","url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120.jpg","name":"01.1041.120 - Watch4Time","isPartOf":{"@id":"https:\/\/watch4time.eu\/#website"},"datePublished":"2017-08-30T08:55:06+00:00","dateModified":"2018-01-22T11:01:06+00:00","breadcrumb":{"@id":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120.jpg#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/watch4time.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Wenger Urban Classic","item":"https:\/\/watch4time.eu\/de\/shop\/wenger-urban-classic\/"},{"@type":"ListItem","position":3,"name":"01.1041.120"}]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120.jpg'><img width=\"400\" height=\"400\" src=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120-400x400.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120-400x400.jpg 400w, https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120-280x280.jpg 280w, https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120-768x768.jpg 768w, https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120-800x800.jpg 800w, https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120-130x130.jpg 130w, https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120-600x600.jpg 600w, https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120.jpg 1024w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1024,"height":1024,"file":"2017\/08\/01.1041.120.jpg","sizes":{"thumbnail":{"file":"01.1041.120-280x280.jpg","width":280,"height":280,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120-280x280.jpg"},"medium":{"file":"01.1041.120-400x400.jpg","width":400,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120-400x400.jpg"},"medium_large":{"file":"01.1041.120-768x768.jpg","width":768,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120-768x768.jpg"},"large":{"file":"01.1041.120-800x800.jpg","width":800,"height":800,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120-800x800.jpg"},"shop_thumbnail":{"file":"01.1041.120-130x130.jpg","width":130,"height":130,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120-130x130.jpg"},"shop_catalog":{"file":"01.1041.120-247x300.jpg","width":247,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120-247x300.jpg"},"shop_single":{"file":"01.1041.120-600x600.jpg","width":600,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120-600x600.jpg"},"full":{"file":"01.1041.120.jpg","width":1024,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":17847,"source_url":"https:\/\/watch4time.eu\/wp-content\/uploads\/2017\/08\/01.1041.120.jpg","_links":{"self":[{"href":"https:\/\/watch4time.eu\/de\/wp-json\/wp\/v2\/media\/6668"}],"collection":[{"href":"https:\/\/watch4time.eu\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/watch4time.eu\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/watch4time.eu\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/watch4time.eu\/de\/wp-json\/wp\/v2\/comments?post=6668"}]}}